{"id":3709,"date":"2014-09-29T14:31:17","date_gmt":"2014-09-29T12:31:17","guid":{"rendered":"https:\/\/www.lestanzedisantacroce.com\/agenda\/2014\/09\/29\/picasso-firenze-2\/"},"modified":"2015-12-30T10:41:32","modified_gmt":"2015-12-30T09:41:32","slug":"picasso-firenze","status":"publish","type":"post","link":"https:\/\/www.lestanzedisantacroce.com\/it\/agenda\/2014\/09\/29\/picasso-firenze\/","title":{"rendered":"Picasso a Firenze"},"content":{"rendered":"<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 18.0pt;\">Dal <strong>20 settembre 2014 Palazzo Strozzi a Firenze<\/strong> riporta l\u2019attenzione sull\u2019arte moderna con un nuovo importante evento dedicato a uno dei pi\u00f9 grandi maestri della <strong>pittura del XX secolo<\/strong>: Pablo Picasso.<br \/>\nLa mostra accoglie circa <strong>90 opere della produzione di Picasso e di altri artisti<\/strong> tra dipinti, sculture, disegni.\u00a0Tra le opere esposte sono presenti celebri capolavori come il\u00a0Ritratto di Dora Maar, la\u00a0Testa di cavallo\u00a0e\u00a0Il pittore e la modella\u00a0di Picasso,\u00a0Siurana, il sentiero\u00a0di Mir\u00f3 e inoltre i disegni, le incisioni e i dipinti preparatori di Picasso per il grande capolavoro\u00a0Guernica, mai esposti in numero cos\u00ec elevato fuori dalla Spagna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 20 settembre 2014 Palazzo Strozzi a Firenze riporta l\u2019attenzione sull\u2019arte moderna con un nuovo importante evento dedicato a uno dei pi\u00f9 grandi maestri della pittura del XX secolo: Pablo Picasso. La mostra accoglie circa 90 opere della produzione di [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[121,122,191,156,157,192],"class_list":["post-3709","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-firenze","tag-firenze-it","tag-florence-it","tag-pablo-picasso-it","tag-palazzo-strozzi-it","tag-picasso-it","tag-picasso-e-la-modernita-spagnola-it"],"_links":{"self":[{"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/posts\/3709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/comments?post=3709"}],"version-history":[{"count":0,"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/posts\/3709\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/media\/3116"}],"wp:attachment":[{"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/media?parent=3709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/categories?post=3709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lestanzedisantacroce.com\/it\/wp-json\/wp\/v2\/tags?post=3709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}